{"id":367,"date":"2023-05-26T12:47:27","date_gmt":"2023-05-26T07:17:27","guid":{"rendered":"https:\/\/tradinglabacademy.in\/?page_id=367"},"modified":"2023-05-26T12:47:27","modified_gmt":"2023-05-26T07:17:27","slug":"inquiry-form","status":"publish","type":"page","link":"https:\/\/tradinglabacademy.in\/index.php\/inquiry-form\/","title":{"rendered":"Inquiry Form"},"content":{"rendered":"\n<p>Please fill the form<\/p>\n\n\n<div class=\"wpforms-container wpforms-container-full wpforms-block wpforms-block-664748a7-b7e5-4544-b484-92f302abd85c wpforms-render-modern\" id=\"wpforms-361\"><form id=\"wpforms-form-361\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"361\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/index.php\/wp-json\/wp\/v2\/pages\/367\" data-token=\"ab8197f94f447b0b11824c87243ac8ae\" data-token-time=\"1778676024\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div class=\"wpforms-hidden\" id=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/div><div class=\"wpforms-field-container\"><div id=\"wpforms-361-field_0-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"0\"><fieldset><legend class=\"wpforms-field-label\">Name <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><div class=\"wpforms-field-row wpforms-field-medium\"><div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-361-field_0\" class=\"wpforms-field-name-first wpforms-field-required\" name=\"wpforms[fields][0][first]\" aria-errormessage=\"wpforms-361-field_0-error\" required><label for=\"wpforms-361-field_0\" class=\"wpforms-field-sublabel after\">First<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-361-field_0-last\" class=\"wpforms-field-name-last wpforms-field-required\" name=\"wpforms[fields][0][last]\" aria-errormessage=\"wpforms-361-field_0-last-error\" required><label for=\"wpforms-361-field_0-last\" class=\"wpforms-field-sublabel after\">Last<\/label><\/div><\/div><\/fieldset><\/div><div id=\"wpforms-361-field_7-container\" class=\"wpforms-field wpforms-field-number\" data-field-id=\"7\"><label class=\"wpforms-field-label\" for=\"wpforms-361-field_7\">mobile number <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"number\" id=\"wpforms-361-field_7\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][7]\" step=\"any\" aria-errormessage=\"wpforms-361-field_7-error\" required><\/div><div id=\"wpforms-361-field_1-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"1\"><label class=\"wpforms-field-label\" for=\"wpforms-361-field_1\">Email <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-361-field_1\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][1]\" spellcheck=\"false\" aria-errormessage=\"wpforms-361-field_1-error\" required><\/div><div id=\"wpforms-361-field_3-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-classic\" data-field-id=\"3\"><label class=\"wpforms-field-label\" for=\"wpforms-361-field_3\">Course Selection<\/label><select id=\"wpforms-361-field_3\" class=\"wpforms-field-medium\" name=\"wpforms[fields][3]\"><option value=\"Intraday\" >Intraday<\/option><option value=\"Futures &amp; Options\" >Futures &amp; Options<\/option><option value=\"Stock Selection\" >Stock Selection<\/option><\/select><\/div><div id=\"wpforms-361-field_5-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-classic\" data-field-id=\"5\"><label class=\"wpforms-field-label\" for=\"wpforms-361-field_5\">Knowledge about stock Market<\/label><select id=\"wpforms-361-field_5\" class=\"wpforms-field-medium\" name=\"wpforms[fields][5]\"><option value=\"Beginner\" >Beginner<\/option><option value=\"Intermediate level\" >Intermediate level<\/option><option value=\"Advance level\" >Advance level<\/option><\/select><\/div><div id=\"wpforms-361-field_4-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-classic\" data-field-id=\"4\"><label class=\"wpforms-field-label\" for=\"wpforms-361-field_4\">Course Selection<\/label><select id=\"wpforms-361-field_4\" class=\"wpforms-field-medium\" name=\"wpforms[fields][4]\"><option value=\"Intraday\" >Intraday<\/option><option value=\"Futures &amp; Options\" >Futures &amp; Options<\/option><option value=\"Stock Selection\" >Stock Selection<\/option><\/select><\/div><div id=\"wpforms-361-field_6-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-classic\" data-field-id=\"6\"><label class=\"wpforms-field-label\" for=\"wpforms-361-field_6\">Occupation<\/label><select id=\"wpforms-361-field_6\" class=\"wpforms-field-medium\" name=\"wpforms[fields][6]\"><option value=\"Student\" >Student<\/option><option value=\"Working Professional\/Business\" >Working Professional\/Business<\/option><option value=\"House Wife\" >House Wife<\/option><\/select><\/div><div id=\"wpforms-361-field_2-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-361-field_2\">Comment or Message<\/label><textarea id=\"wpforms-361-field_2\" class=\"wpforms-field-medium\" name=\"wpforms[fields][2]\" aria-errormessage=\"wpforms-361-field_2-error\" ><\/textarea><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"361\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/tradinglabacademy.in\/index.php\/wp-json\/wp\/v2\/pages\/367\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-361\" class=\"wpforms-submit\" data-alt-text=\"Sending\u2026\" data-submit-text=\"Submit\" aria-live=\"assertive\" value=\"wpforms-submit\">Submit<\/button><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/tradinglabacademy.in\/wp-content\/plugins\/wpforms-lite\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Loading\"><\/div><\/form><\/div>  <!-- .wpforms-container -->","protected":false},"excerpt":{"rendered":"<p>Please fill the form<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-367","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/tradinglabacademy.in\/index.php\/wp-json\/wp\/v2\/pages\/367","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tradinglabacademy.in\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/tradinglabacademy.in\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/tradinglabacademy.in\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tradinglabacademy.in\/index.php\/wp-json\/wp\/v2\/comments?post=367"}],"version-history":[{"count":1,"href":"https:\/\/tradinglabacademy.in\/index.php\/wp-json\/wp\/v2\/pages\/367\/revisions"}],"predecessor-version":[{"id":368,"href":"https:\/\/tradinglabacademy.in\/index.php\/wp-json\/wp\/v2\/pages\/367\/revisions\/368"}],"wp:attachment":[{"href":"https:\/\/tradinglabacademy.in\/index.php\/wp-json\/wp\/v2\/media?parent=367"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}